{"id":9317,"date":"2025-11-27T17:16:19","date_gmt":"2025-11-27T09:16:19","guid":{"rendered":"https:\/\/dryingplant.com\/?p=9317"},"modified":"2025-11-27T17:16:20","modified_gmt":"2025-11-27T09:16:20","slug":"sierra-leone-customer-hookah-charcoal-drying-machine-project","status":"publish","type":"post","link":"https:\/\/dryingplant.com\/fr\/sierra-leone-customer-hookah-charcoal-drying-machine-project\/","title":{"rendered":"Projet de machine de s\u00e9chage de charbon de hookah pour le client de Sierra Leone"},"content":{"rendered":"<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-top\"     data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;9317&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;6&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.8&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.8\\\/5 - (6 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Sierra Leone Customer \u2013 Hookah Charcoal Drying Machine Project&quot;,&quot;width&quot;:&quot;136.7&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 136.7px;\">             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4.8\/5 - (6 votes)    <\/div>     <\/div>  <p class=\"wp-block-paragraph\">Le 22 novembre 2025, la machine de s\u00e9chage de charbon \u00e0 narguil\u00e9 pour notre client en Sierra Leone a \u00e9t\u00e9 exp\u00e9di\u00e9e avec succ\u00e8s.<\/p>    <p class=\"wp-block-paragraph\">Ce cas montre comment le client a choisi de travailler avec Shuliy pour construire une chambre de s\u00e9chage de charbon \u00e0 narguil\u00e9 avec 10 chariots en raison de la faible efficacit\u00e9 et de l'instabilit\u00e9 du s\u00e9chage traditionnel au soleil. Shuliy a personnalis\u00e9 un syst\u00e8me de chauffage au bois et au charbon bas\u00e9 sur la tension locale et les besoins de production du client. Le nouveau syst\u00e8me permet un s\u00e9chage efficace, stable et contr\u00f4lable, am\u00e9liorant consid\u00e9rablement la qualit\u00e9 et la production des produits.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Shisha-charcoal-drying-machine.webp\" alt=\"Machine de s\u00e9chage de charbon \u00e0 narguil\u00e9\" class=\"wp-image-9323\" title=\"\" srcset=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Shisha-charcoal-drying-machine.webp 720w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Shisha-charcoal-drying-machine-240x180.webp 240w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Shisha-charcoal-drying-machine-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Machine de s\u00e9chage de charbon \u00e0 narguil\u00e9<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\">Contexte du client<\/h2>    <p class=\"wp-block-paragraph\">Le client vient de Sierra Leone et produit principalement du charbon \u00e0 narguil\u00e9 et d'autres produits en charbon. En raison de la longue saison des pluies et de l'humidit\u00e9 \u00e9lev\u00e9e dans la r\u00e9gion, le s\u00e9chage traditionnel en ext\u00e9rieur ne peut pas garantir une s\u00e9cheresse ad\u00e9quate. Cela entra\u00eene souvent un s\u00e9chage in\u00e9gal, de la moisissure, un retour d'humidit\u00e9 et des cycles de production instables.<\/p>    <p class=\"wp-block-paragraph\">Pour augmenter la production, am\u00e9liorer la qualit\u00e9 du produit et r\u00e9pondre \u00e0 des normes d'exportation plus \u00e9lev\u00e9es, le client a d\u00e9cid\u00e9 d'acheter un \u00e9quipement de s\u00e9chage industriel.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Hookah-charcoal.webp\" alt=\"Charbon \u00e0 narguil\u00e9\" class=\"wp-image-9325\" title=\"\" srcset=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Hookah-charcoal.webp 720w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Hookah-charcoal-240x180.webp 240w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Hookah-charcoal-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Charbon \u00e0 narguil\u00e9<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\">Solution Shuliy<\/h2>    <p class=\"wp-block-paragraph translation-block\">En fonction de la capacit\u00e9 de s\u00e9chage du client et des conditions \u00e9nerg\u00e9tiques locales, Shuliy a fourni une machine de s\u00e9chage de charbon \u00e0 narguil\u00e9<strong><a href=\"https:\/\/dryingplant.com\/fr\/drying-room\/\"> avec 10 chariots en bois et charbon chauff\u00e9s<\/a><\/strong>.<\/p>    <p class=\"wp-block-paragraph translation-block\"><strong>Caract\u00e9ristiques cl\u00e9s de la solution :<\/strong><\/p>    <ul class=\"wp-block-list\"> <li>Utilise du bois et du charbon comme source d'\u00e9nergie \u2014 \u00e9conomie d'\u00e9nergie, facile \u00e0 obtenir, et adapt\u00e9 aux conditions de combustible locales.<\/li>    <li>Une chambre de s\u00e9chage de 10 m\u00e8tres permet un s\u00e9chage continu par lots pour am\u00e9liorer l'efficacit\u00e9.<\/li>    <li>\u00c9quip\u00e9 de 10 chariots et 120 plateaux pour un chargement de grande capacit\u00e9 et une r\u00e9partition plus uniforme du mat\u00e9riau.<\/li>    <li>Un panneau de contr\u00f4le intelligent surveille et ajuste la temp\u00e9rature pour assurer un chauffage uniforme et une qualit\u00e9 constante du produit.<\/li>    <li>Un transformateur est inclus pour s'adapter au r\u00e9seau \u00e9lectrique local et maintenir le syst\u00e8me en fonctionnement stable.<\/li> <\/ul>    <p class=\"wp-block-paragraph\">Cette solution r\u00e9sout les probl\u00e8mes de s\u00e9chage lent, de s\u00e9chage in\u00e9gal et de d\u00e9pendance aux conditions m\u00e9t\u00e9orologiques, permettant un fonctionnement stable et par tous les temps.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/charcoal-dryer-machine.webp\" alt=\"Machine de s\u00e9chage de charbon\" class=\"wp-image-9319\" title=\"\" srcset=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/charcoal-dryer-machine.webp 720w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/charcoal-dryer-machine-240x180.webp 240w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/charcoal-dryer-machine-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Machine de s\u00e9chage de charbon<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\">Param\u00e8tres techniques<\/h2>    <figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Article<\/th><th>Param\u00e8tre<\/th><\/tr><\/thead><tbody><tr><td>Tension \u00e9lectrique<\/td><td>415V, 50Hz, triphas\u00e9<\/td><\/tr><tr><td>\u00c9nergie \u00e9lectrique<\/td><td>5 kW<\/td><\/tr><tr><td>Type de chambre de s\u00e9chage<\/td><td>Machine de s\u00e9chage de charbon \u00e0 narguil\u00e9 avec 10 chariots<\/td><\/tr><tr><td>Source de chaleur<\/td><td>Chauffage au bois et au charbon<\/td><\/tr><tr><td>Taille de la chambre de s\u00e9chage<\/td><td>10m \u00d7 2,3m \u00d7 2,5m<\/td><\/tr><tr><td>Configuration<\/td><td>10 chariots, 120 plateaux, armoire de contr\u00f4le<\/td><\/tr><tr><td>Configuration suppl\u00e9mentaire<\/td><td>Transformateur (adapt\u00e9 \u00e0 la tension locale)<\/td><\/tr><\/tbody><\/table><\/figure>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/charcoal-briquette-dryer-machine.webp\" alt=\"Machine de s\u00e9chage de briquettes de charbon\" class=\"wp-image-9318\" title=\"\" srcset=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/charcoal-briquette-dryer-machine.webp 720w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/charcoal-briquette-dryer-machine-240x180.webp 240w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/charcoal-briquette-dryer-machine-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Machine de s\u00e9chage de briquettes de charbon<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\">Service apr\u00e8s-vente<\/h2>    <p class=\"wp-block-paragraph\">Pour aider le client \u00e0 mettre rapidement l'\u00e9quipement en production, Shuliy a fourni :<\/p>    <ul class=\"wp-block-list\"> <li><strong>Guidance \u00e0 distance pour l'installation :<\/strong> Les ing\u00e9nieurs ont guid\u00e9 le client via vid\u00e9o et dessins pour compl\u00e9ter l'assemblage de la chambre de s\u00e9chage de charbon \u00e0 narguil\u00e9.<\/li>    <li><strong>Formation \u00e0 l'exploitation :<\/strong> Formation d\u00e9taill\u00e9e sur l'allumage, le contr\u00f4le de la temp\u00e9rature et les m\u00e9thodes de chargement.<\/li>    <li><strong>Support pour le d\u00e9pannage de la production : <\/strong>Assistance pour d\u00e9finir la meilleure courbe de temp\u00e9rature et de temps de s\u00e9chage afin d'assurer la qualit\u00e9 du produit.<\/li>    <li><strong>Fourniture de pi\u00e8ces de rechange et support technique \u00e0 long terme :<\/strong> Assurer un fonctionnement stable \u00e0 long terme.<\/li> <\/ul>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"9322\" src=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Shisha-charcoal-dryer.webp\" alt=\"S\u00e8che-charbon \u00e0 narguil\u00e9\" class=\"wp-image-9322\" title=\"\" srcset=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Shisha-charcoal-dryer.webp 720w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Shisha-charcoal-dryer-240x180.webp 240w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Shisha-charcoal-dryer-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">S\u00e8che-charbon \u00e0 narguil\u00e9<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"9320\" src=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Control-cabinet.webp\" alt=\"Armoire de contr\u00f4le\" class=\"wp-image-9320\" title=\"\" srcset=\"https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Control-cabinet.webp 720w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Control-cabinet-240x180.webp 240w, https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/Control-cabinet-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Armoire de contr\u00f4le<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Travailler avec Shuliy<\/h2>    <p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0 cette coop\u00e9ration, le client en Sierra Leone a r\u00e9alis\u00e9 une mise \u00e0 niveau majeure de la production de charbon \u00e0 narguil\u00e9 :<\/p>    <ul class=\"wp-block-list\"> <li>Vitesse de s\u00e9chage am\u00e9lior\u00e9e de 2 \u00e0 3 fois<\/li>    <li>Contenu en humidit\u00e9 stable et meilleur contr\u00f4le de la qualit\u00e9<\/li>    <li>Aucun impact de la saison des pluies, permettant une production toute l'ann\u00e9e<\/li>    <li>R\u00e9duction des co\u00fbts de production et renforcement de la comp\u00e9titivit\u00e9 sur le march\u00e9<\/li> <\/ul>    <p class=\"wp-block-paragraph\">Shuliy continuera \u00e0 fournir des solutions d'expansion futures et un support technique, aidant le client \u00e0 augmenter sa capacit\u00e9 de production et \u00e0 se d\u00e9velopper sur le march\u00e9 du charbon \u00e0 narguil\u00e9.<\/p>    <p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>On November 22, 2025, the hookah charcoal drying machine for our Sierra Leone customer was successfully shipped. This case shows how the customer chose to work with Shuliy to build a 10-trolley hookah charcoal drying room due to the low efficiency and instability of traditional sun-drying. Shuliy customized a firewood-and-coal heating system based on the&#8230;<\/p>","protected":false},"author":1,"featured_media":9318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-9317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case"],"taxonomy_info":{"category":[{"value":1,"label":"Case"}]},"featured_image_src_large":["https:\/\/dryingplant.com\/wp-content\/uploads\/2025\/11\/charcoal-briquette-dryer-machine.webp",720,540,false],"author_info":{"display_name":"DryingPlant.Com","author_link":"https:\/\/dryingplant.com\/fr\/author\/drying\/"},"comment_info":0,"category_info":[{"term_id":1,"name":"Case","slug":"case","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":33,"filter":"raw","cat_ID":1,"category_count":33,"category_description":"","cat_name":"Case","category_nicename":"case","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/posts\/9317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/comments?post=9317"}],"version-history":[{"count":0,"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/posts\/9317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/media\/9318"}],"wp:attachment":[{"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/media?parent=9317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/categories?post=9317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dryingplant.com\/fr\/wp-json\/wp\/v2\/tags?post=9317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}